{"id":353,"count":6,"description":"","link":"https:\/\/tradehouse.com.eg\/ar\/category\/big-bass-de\/","name":"big bass de","slug":"big-bass-de","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/tradehouse.com.eg\/ar\/category\/big-bass-de\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/353\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/category\\\/big-bass-de\\\/#listItem\",\"name\":\"big bass de\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/category\\\/big-bass-de\\\/#listItem\",\"position\":2,\"name\":\"big bass de\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/353\\\/#collectionpage\",\"url\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/353\\\/\",\"name\":\"big bass de - Trade House\",\"inLanguage\":\"ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/353\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/#organization\",\"name\":\"Trade House\",\"description\":\"Your Way For Smart World.\",\"url\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/\",\"name\":\"Trade House\",\"description\":\"Your Way For Smart World.\",\"inLanguage\":\"ar\",\"publisher\":{\"@id\":\"https:\\\/\\\/tradehouse.com.eg\\\/ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"big bass de - Trade House","description":"","canonical_url":"https:\/\/tradehouse.com.eg\/ar\/category\/big-bass-de\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/tradehouse.com.eg\/ar\/wp-json\/wp\/v2\/categories\/353\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/tradehouse.com.eg\/ar#listItem","position":1,"name":"Home","item":"https:\/\/tradehouse.com.eg\/ar","nextItem":{"@type":"ListItem","@id":"https:\/\/tradehouse.com.eg\/ar\/category\/big-bass-de\/#listItem","name":"big bass de"}},{"@type":"ListItem","@id":"https:\/\/tradehouse.com.eg\/ar\/category\/big-bass-de\/#listItem","position":2,"name":"big bass de","previousItem":{"@type":"ListItem","@id":"https:\/\/tradehouse.com.eg\/ar#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/tradehouse.com.eg\/ar\/wp-json\/wp\/v2\/categories\/353\/#collectionpage","url":"https:\/\/tradehouse.com.eg\/ar\/wp-json\/wp\/v2\/categories\/353\/","name":"big bass de - Trade House","inLanguage":"ar","isPartOf":{"@id":"https:\/\/tradehouse.com.eg\/ar\/#website"},"breadcrumb":{"@id":"https:\/\/tradehouse.com.eg\/ar\/wp-json\/wp\/v2\/categories\/353\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/tradehouse.com.eg\/ar\/#organization","name":"Trade House","description":"Your Way For Smart World.","url":"https:\/\/tradehouse.com.eg\/ar\/"},{"@type":"WebSite","@id":"https:\/\/tradehouse.com.eg\/ar\/#website","url":"https:\/\/tradehouse.com.eg\/ar\/","name":"Trade House","description":"Your Way For Smart World.","inLanguage":"ar","publisher":{"@id":"https:\/\/tradehouse.com.eg\/ar\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tradehouse.com.eg\/ar\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tbig bass de\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/tradehouse.com.eg\/ar"},{"label":"big bass de","link":"https:\/\/tradehouse.com.eg\/ar\/category\/big-bass-de\/"}],"_links":{"self":[{"href":"https:\/\/tradehouse.com.eg\/ar\/wp-json\/wp\/v2\/categories\/353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tradehouse.com.eg\/ar\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/tradehouse.com.eg\/ar\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/tradehouse.com.eg\/ar\/wp-json\/wp\/v2\/posts?categories=353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}